{"id":11757,"date":"2022-07-11T12:42:17","date_gmt":"2022-07-11T09:42:17","guid":{"rendered":"https:\/\/www.athena-cbh.com\/zephyr-restaurant-adults-only\/"},"modified":"2024-09-16T19:05:43","modified_gmt":"2024-09-16T16:05:43","slug":"zephyr-restaurant-adults-only","status":"publish","type":"page","link":"https:\/\/www.athena-cbh.com\/it\/couples-holidays\/zephyr-restaurant-adults-only\/","title":{"rendered":"Ristorante Zephyr (solo per adulti)"},"content":{"rendered":"<p>Il Ristorante Zephyr opera esclusivamente per gli ospiti di et\u00e0 superiore ai 16 anni, offrendo un ricco buffet mediterraneo per la colazione e una cucina dai sontuosi sapori internazionali per la cena \u00e0 la carte\/Table d&#8217;h\u00f4tel.<br \/>\nAperto per: Colazione a buffet mediterraneo e cena \u00e0 la carte \/ Table d&#8217;h\u00f4tel (\u00e8 necessaria la prenotazione). Anche gli ospiti in mezza pensione possono gustare una cena a menu fisso di quattro portate senza pagare un supplemento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Ristorante Zephyr opera esclusivamente per gli ospiti di et\u00e0 superiore ai 16 anni, offrendo un ricco buffet mediterraneo per la colazione e una cucina dai sontuosi sapori internazionali per la cena \u00e0 la carte\/Table d&#8217;h\u00f4tel. Aperto per: Colazione a buffet mediterraneo e cena \u00e0 la carte \/ Table d&#8217;h\u00f4tel (\u00e8 necessaria la prenotazione). Anche<\/p>\n","protected":false},"author":100,"featured_media":11758,"parent":11843,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-11757","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ristorante Zephyr (solo per adulti) - Athena Beach Hotel<\/title>\n<meta name=\"description\" content=\"Il ristorante Zephyr \u00e8 l&#039;ambiente adulto perfetto per una colazione, un pranzo e una cena tranquilli, con un mix di opzioni mediterranee a buffet e \u00e0 la carte.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.athena-cbh.com\/it\/couples-holidays\/zephyr-restaurant-adults-only\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ristorante Zephyr (solo per adulti) - Athena Beach Hotel\" \/>\n<meta property=\"og:description\" content=\"Il ristorante Zephyr \u00e8 l&#039;ambiente adulto perfetto per una colazione, un pranzo e una cena tranquilli, con un mix di opzioni mediterranee a buffet e \u00e0 la carte.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.athena-cbh.com\/it\/couples-holidays\/zephyr-restaurant-adults-only\/\" \/>\n<meta property=\"og:site_name\" content=\"Athena Beach Hotel\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-16T16:05:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.athena-cbh.com\/app\/uploads\/sites\/20\/2022\/07\/29-ATHENA-BEACH-HOTEL-ZEPHYR-A-LA-CARTE-RESTAURANT-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1703\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.athena-cbh.com\\\/it\\\/couples-holidays\\\/zephyr-restaurant-adults-only\\\/\",\"url\":\"https:\\\/\\\/www.athena-cbh.com\\\/it\\\/couples-holidays\\\/zephyr-restaurant-adults-only\\\/\",\"name\":\"Ristorante Zephyr (solo per adulti) - Athena Beach Hotel\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.athena-cbh.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.athena-cbh.com\\\/it\\\/couples-holidays\\\/zephyr-restaurant-adults-only\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.athena-cbh.com\\\/it\\\/couples-holidays\\\/zephyr-restaurant-adults-only\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.athena-cbh.com\\\/app\\\/uploads\\\/sites\\\/20\\\/2022\\\/07\\\/29-ATHENA-BEACH-HOTEL-ZEPHYR-A-LA-CARTE-RESTAURANT-scaled.jpg\",\"datePublished\":\"2022-07-11T09:42:17+00:00\",\"dateModified\":\"2024-09-16T16:05:43+00:00\",\"description\":\"Il ristorante Zephyr \u00e8 l'ambiente adulto perfetto per una colazione, un pranzo e una cena tranquilli, con un mix di opzioni mediterranee a buffet e \u00e0 la carte.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.athena-cbh.com\\\/it\\\/couples-holidays\\\/zephyr-restaurant-adults-only\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.athena-cbh.com\\\/it\\\/couples-holidays\\\/zephyr-restaurant-adults-only\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.athena-cbh.com\\\/it\\\/couples-holidays\\\/zephyr-restaurant-adults-only\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.athena-cbh.com\\\/app\\\/uploads\\\/sites\\\/20\\\/2022\\\/07\\\/29-ATHENA-BEACH-HOTEL-ZEPHYR-A-LA-CARTE-RESTAURANT-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.athena-cbh.com\\\/app\\\/uploads\\\/sites\\\/20\\\/2022\\\/07\\\/29-ATHENA-BEACH-HOTEL-ZEPHYR-A-LA-CARTE-RESTAURANT-scaled.jpg\",\"width\":2560,\"height\":1703},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.athena-cbh.com\\\/it\\\/couples-holidays\\\/zephyr-restaurant-adults-only\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.athena-cbh.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vacanze di coppia\",\"item\":\"https:\\\/\\\/www.athena-cbh.com\\\/it\\\/couples-holidays\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ristorante Zephyr (solo per adulti)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.athena-cbh.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.athena-cbh.com\\\/it\\\/\",\"name\":\"Athena Beach Hotel\",\"description\":\"Constantinou Bros Athena Beach Hotel, 4 star hotel in Paphos Cyprus\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.athena-cbh.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ristorante Zephyr (solo per adulti) - Athena Beach Hotel","description":"Il ristorante Zephyr \u00e8 l'ambiente adulto perfetto per una colazione, un pranzo e una cena tranquilli, con un mix di opzioni mediterranee a buffet e \u00e0 la carte.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.athena-cbh.com\/it\/couples-holidays\/zephyr-restaurant-adults-only\/","og_locale":"it_IT","og_type":"article","og_title":"Ristorante Zephyr (solo per adulti) - Athena Beach Hotel","og_description":"Il ristorante Zephyr \u00e8 l'ambiente adulto perfetto per una colazione, un pranzo e una cena tranquilli, con un mix di opzioni mediterranee a buffet e \u00e0 la carte.","og_url":"https:\/\/www.athena-cbh.com\/it\/couples-holidays\/zephyr-restaurant-adults-only\/","og_site_name":"Athena Beach Hotel","article_modified_time":"2024-09-16T16:05:43+00:00","og_image":[{"width":2560,"height":1703,"url":"https:\/\/www.athena-cbh.com\/app\/uploads\/sites\/20\/2022\/07\/29-ATHENA-BEACH-HOTEL-ZEPHYR-A-LA-CARTE-RESTAURANT-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.athena-cbh.com\/it\/couples-holidays\/zephyr-restaurant-adults-only\/","url":"https:\/\/www.athena-cbh.com\/it\/couples-holidays\/zephyr-restaurant-adults-only\/","name":"Ristorante Zephyr (solo per adulti) - Athena Beach Hotel","isPartOf":{"@id":"https:\/\/www.athena-cbh.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.athena-cbh.com\/it\/couples-holidays\/zephyr-restaurant-adults-only\/#primaryimage"},"image":{"@id":"https:\/\/www.athena-cbh.com\/it\/couples-holidays\/zephyr-restaurant-adults-only\/#primaryimage"},"thumbnailUrl":"https:\/\/www.athena-cbh.com\/app\/uploads\/sites\/20\/2022\/07\/29-ATHENA-BEACH-HOTEL-ZEPHYR-A-LA-CARTE-RESTAURANT-scaled.jpg","datePublished":"2022-07-11T09:42:17+00:00","dateModified":"2024-09-16T16:05:43+00:00","description":"Il ristorante Zephyr \u00e8 l'ambiente adulto perfetto per una colazione, un pranzo e una cena tranquilli, con un mix di opzioni mediterranee a buffet e \u00e0 la carte.","breadcrumb":{"@id":"https:\/\/www.athena-cbh.com\/it\/couples-holidays\/zephyr-restaurant-adults-only\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.athena-cbh.com\/it\/couples-holidays\/zephyr-restaurant-adults-only\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.athena-cbh.com\/it\/couples-holidays\/zephyr-restaurant-adults-only\/#primaryimage","url":"https:\/\/www.athena-cbh.com\/app\/uploads\/sites\/20\/2022\/07\/29-ATHENA-BEACH-HOTEL-ZEPHYR-A-LA-CARTE-RESTAURANT-scaled.jpg","contentUrl":"https:\/\/www.athena-cbh.com\/app\/uploads\/sites\/20\/2022\/07\/29-ATHENA-BEACH-HOTEL-ZEPHYR-A-LA-CARTE-RESTAURANT-scaled.jpg","width":2560,"height":1703},{"@type":"BreadcrumbList","@id":"https:\/\/www.athena-cbh.com\/it\/couples-holidays\/zephyr-restaurant-adults-only\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.athena-cbh.com\/it\/"},{"@type":"ListItem","position":2,"name":"Vacanze di coppia","item":"https:\/\/www.athena-cbh.com\/it\/couples-holidays\/"},{"@type":"ListItem","position":3,"name":"Ristorante Zephyr (solo per adulti)"}]},{"@type":"WebSite","@id":"https:\/\/www.athena-cbh.com\/it\/#website","url":"https:\/\/www.athena-cbh.com\/it\/","name":"Athena Beach Hotel","description":"Constantinou Bros Athena Beach Hotel, 4 star hotel in Paphos Cyprus","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.athena-cbh.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/www.athena-cbh.com\/it\/wp-json\/wp\/v2\/pages\/11757","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.athena-cbh.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.athena-cbh.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.athena-cbh.com\/it\/wp-json\/wp\/v2\/users\/100"}],"replies":[{"embeddable":true,"href":"https:\/\/www.athena-cbh.com\/it\/wp-json\/wp\/v2\/comments?post=11757"}],"version-history":[{"count":1,"href":"https:\/\/www.athena-cbh.com\/it\/wp-json\/wp\/v2\/pages\/11757\/revisions"}],"predecessor-version":[{"id":18542,"href":"https:\/\/www.athena-cbh.com\/it\/wp-json\/wp\/v2\/pages\/11757\/revisions\/18542"}],"up":[{"embeddable":true,"href":"https:\/\/www.athena-cbh.com\/it\/wp-json\/wp\/v2\/pages\/11843"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.athena-cbh.com\/it\/wp-json\/wp\/v2\/media\/11758"}],"wp:attachment":[{"href":"https:\/\/www.athena-cbh.com\/it\/wp-json\/wp\/v2\/media?parent=11757"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}